{"id":83971,"date":"2025-09-26T19:08:06","date_gmt":"2025-09-26T17:08:06","guid":{"rendered":"https:\/\/www.fedaiisf.it\/?p=83971"},"modified":"2025-09-26T19:08:06","modified_gmt":"2025-09-26T17:08:06","slug":"catania-fedaiisf-a-pharmaevolution-il-programma","status":"publish","type":"post","link":"https:\/\/www.fedaiisf.it\/en\/catania-fedaiisf-a-pharmaevolution-il-programma\/","title":{"rendered":"Catania. Fedaiisf a Pharmaevolution. Il programma"},"content":{"rendered":"<p>The <a href=\"https:\/\/www.pharmevolution.it\/programma-generale.pdf\" target=\"_blank\" rel=\"noopener\">programma ufficiale di Pharmevolution<\/a>.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-83974 alignright\" src=\"https:\/\/www.fedaiisf.it\/wp-content\/uploads\/2025\/09\/locandina-pharmevolution-2025.png\" alt=\"\" width=\"353\" height=\"342\" srcset=\"https:\/\/www.fedaiisf.it\/wp-content\/uploads\/2025\/09\/locandina-pharmevolution-2025.png 1102w, https:\/\/www.fedaiisf.it\/wp-content\/uploads\/2025\/09\/locandina-pharmevolution-2025-300x291.png 300w, https:\/\/www.fedaiisf.it\/wp-content\/uploads\/2025\/09\/locandina-pharmevolution-2025-1024x992.png 1024w, https:\/\/www.fedaiisf.it\/wp-content\/uploads\/2025\/09\/locandina-pharmevolution-2025-768x744.png 768w, https:\/\/www.fedaiisf.it\/wp-content\/uploads\/2025\/09\/locandina-pharmevolution-2025-12x12.png 12w\" sizes=\"auto, (max-width: 353px) 100vw, 353px\" \/>Il convegno Fedaiisf si terr\u00e0 venerd\u00ec 10 ottobre dalle 16.30 alle 19.00.<br \/>\nIl convegno avr\u00e0 due sessioni<\/p>\n<ol>\n<li>informatore scientifico del farmaco e del parafarmaco una professione in evoluzione. Stato dell\u2019arte e prospettive<\/li>\n<li>Presentazione premio laurea Angelo Passini.<\/li>\n<\/ol>\n<p style=\"font-weight: 400;\">PharmEvolution \u00e8 la fiera \u2013 evento di settore nata nel 2011 per creare un momento di incontro tra tutti gli attori della filiera del farmaco.<\/p>\n<p style=\"font-weight: 400;\">Con 145 espositori, 113 relatori, 7500 mq di spazi espositivi, per tre giorni Catania diventa la Capitale della Farmaceutica, in un evento che coniuga formazione e informazione, incontro tra domanda e offerta, e aggiornamento su beni e servizi di ultima generazione per la farmacia.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-83973\" src=\"https:\/\/www.fedaiisf.it\/wp-content\/uploads\/2025\/09\/Screenshot-2025-09-26-alle-18.44.28.png\" alt=\"\" width=\"1102\" height=\"1046\" srcset=\"https:\/\/www.fedaiisf.it\/wp-content\/uploads\/2025\/09\/Screenshot-2025-09-26-alle-18.44.28.png 1102w, https:\/\/www.fedaiisf.it\/wp-content\/uploads\/2025\/09\/Screenshot-2025-09-26-alle-18.44.28-300x285.png 300w, https:\/\/www.fedaiisf.it\/wp-content\/uploads\/2025\/09\/Screenshot-2025-09-26-alle-18.44.28-1024x972.png 1024w, https:\/\/www.fedaiisf.it\/wp-content\/uploads\/2025\/09\/Screenshot-2025-09-26-alle-18.44.28-768x729.png 768w, https:\/\/www.fedaiisf.it\/wp-content\/uploads\/2025\/09\/Screenshot-2025-09-26-alle-18.44.28-13x12.png 13w\" sizes=\"auto, (max-width: 1102px) 100vw, 1102px\" \/><\/p>","protected":false},"excerpt":{"rendered":"<p>Il programma ufficiale di Pharmevolution. Il convegno Fedaiisf si terr\u00e0 venerd\u00ec 10 ottobre dalle 16.30 alle 19.00. Il convegno avr\u00e0 due sessioni informatore scientifico del farmaco e del parafarmaco una professione in evoluzione. Stato dell\u2019arte e prospettive Presentazione premio laurea Angelo Passini. PharmEvolution \u00e8 la fiera \u2013 evento di settore nata nel 2011 per creare &hellip;<\/p>","protected":false},"author":4,"featured_media":83977,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[45,21],"class_list":["post-83971","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie","tag-fedaiisf","tag-informatori-scientifici"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.fedaiisf.it\/en\/wp-json\/wp\/v2\/posts\/83971","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fedaiisf.it\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fedaiisf.it\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fedaiisf.it\/en\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fedaiisf.it\/en\/wp-json\/wp\/v2\/comments?post=83971"}],"version-history":[{"count":1,"href":"https:\/\/www.fedaiisf.it\/en\/wp-json\/wp\/v2\/posts\/83971\/revisions"}],"predecessor-version":[{"id":83975,"href":"https:\/\/www.fedaiisf.it\/en\/wp-json\/wp\/v2\/posts\/83971\/revisions\/83975"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fedaiisf.it\/en\/wp-json\/wp\/v2\/media\/83977"}],"wp:attachment":[{"href":"https:\/\/www.fedaiisf.it\/en\/wp-json\/wp\/v2\/media?parent=83971"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fedaiisf.it\/en\/wp-json\/wp\/v2\/categories?post=83971"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fedaiisf.it\/en\/wp-json\/wp\/v2\/tags?post=83971"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}